{"id":285,"date":"2025-03-19T13:45:42","date_gmt":"2025-03-19T13:45:42","guid":{"rendered":"https:\/\/eventos.alboan.org\/bazkari-solidarioa-irunean\/"},"modified":"2025-04-28T15:40:09","modified_gmt":"2025-04-28T15:40:09","slug":"bazkari-solidarioa-irunean","status":"publish","type":"post","link":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/","title":{"rendered":"Bazkari solidarioa Iru\u00f1ean"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-20416a3c alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-cba13926 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-grayscale wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg\" alt=\"Comida solidaria Pamplona\" class=\"uag-image-182\" width=\"1550\" height=\"600\" title=\"jornada-solidaria-pamplona\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3dfd899b alignfull uagb-is-root-container\">\n<div data-aos= \"fade\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-advanced-heading uagb-block-cd35c1ac\"><h3 class=\"uagb-heading-text\">Bazkari solidarioa Iru\u00f1ean<\/h3><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-91948dea alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-2151326c\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-68fd1db2\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div data-aos= \"fade\" data-aos-duration=\"600\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-e4bb4102 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">IZEN EMAN<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-77983cb4\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div data-aos= \"fade\" data-aos-duration=\"600\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-31134bc4 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><span class=\"uagb-button__icon uagb-button__icon-position-before\"><\/span><div class=\"uagb-button__link\">NIRE INSKRIPZIOA<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2b964e83\"><div class=\"uagb-separator\"><\/div><h5 class=\"uagb-heading-text\">Oinarrizko datuak<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6999edee\"><p class=\"uagb-heading-text\"><strong>Noiz: <\/strong>Igandea, 2024ko urriaren 20an<br><strong>Non:<\/strong> Francisco Bergam\u00edn, 32<br><strong>Hiria:<\/strong> Iru\u00f1a<br><strong>Probintzia:<\/strong> Nafarroa<br><strong>Izen emateko epea:<\/strong> urriaren 18ra arte<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f034d852\"><div class=\"uagb-separator\"><\/div><h5 class=\"uagb-heading-text\">Salneurria<\/h5><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a4354eec\"><p class=\"uagb-heading-text\">Zenbatekoak, inpuestuak barne<br>Plataformaren komisioa ez dago sartuta.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-00848177\"><p class=\"uagb-heading-text\">Menua<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-df34dd27\">\n<div class=\"wp-block-uagb-container uagb-block-5fba0dba\">\n<div class=\"wp-block-uagb-container uagb-block-822ce3de\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-101c4ac7\"><p class=\"uagb-heading-text\">Entsaladilla, ilarrak eta oilaskoa<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f2c5b102\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-160faa78\"><p class=\"uagb-heading-text\">13,00\u20ac<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4c274995\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fa53f303\"><p class=\"uagb-heading-text\">Menu solidarioa<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9b8dec26\">\n<div class=\"wp-block-uagb-container uagb-block-c21d967a\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-624cd772\"><p class=\"uagb-heading-text\">Epea: 2024\/03\/28<br><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9f03921b\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-30caed17\"><p class=\"uagb-heading-text\">Dohainik<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-37627e51\">\n<div data-aos= \"zoom-in\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-image uagb-block-c013c43b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-grayscale wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/JornadaSolidariaCerradasInscripcioinesonline.jpg\" alt=\"Comida solidaria Pamplona\" class=\"uag-image-183\" width=\"678\" height=\"960\" title=\"Comida solidaria Pamplona\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n\n\n<div data-aos= \"flip-up\" data-aos-duration=\"550\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-countdown uagb-block-1ef097ff\"><div class=\"wp-block-uagb-countdown__box wp-block-uagb-countdown__box-days\"><div role=\"timer\" aria-live=\"off\" class=\"wp-block-uagb-countdown__time wp-block-uagb-countdown__time-days\">&#8211;<\/div><div class=\"wp-block-uagb-countdown__label\">D\u00cdAS<\/div><\/div><div class=\"wp-block-uagb-countdown__box wp-block-uagb-countdown__box-hours\"><div role=\"timer\" aria-live=\"off\" class=\"wp-block-uagb-countdown__time wp-block-uagb-countdown__time-hours\">&#8211;<\/div><div class=\"wp-block-uagb-countdown__label\">HORAS<\/div><\/div><div class=\"wp-block-uagb-countdown__box wp-block-uagb-countdown__box-minutes\"><div role=\"timer\" aria-live=\"off\" class=\"wp-block-uagb-countdown__time wp-block-uagb-countdown__time-minutes\">&#8211;<\/div><div class=\"wp-block-uagb-countdown__label\">MINUTOS<\/div><\/div><div class=\"wp-block-uagb-countdown__box wp-block-uagb-countdown__box-seconds\"><div role=\"timer\" aria-live=\"off\" class=\"wp-block-uagb-countdown__time wp-block-uagb-countdown__time-seconds\">&#8211;<\/div><div class=\"wp-block-uagb-countdown__label\">SECONDS<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Alboan Fundazioak, <strong>San Ignacio Ikastetxearekin eta Loyola Zentroarekin<\/strong> elkarlanean, <strong>jardunaldi solidario<\/strong> hau antolatu du, hiriko erdigunetik martxa bat eta 400 lagunentzako bazkaria barne. Ekimenak herrialdeko larrialdi humanitarioaren biktimei laguntzeko dirua biltzea du helburu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Igandean, urriaren 20an, Iru\u00f1ea mobilizatuko da Libanoko gatazkak kaltetutako pertsonei babesa emateko. Alboan Fundazioak, San Ignacio Ikastetxearekin eta Loyola Zentroarekin elkarlanean, elkartasun jardunaldi bat antolatu du hiriko erdigunetik martxa bat eta 400 lagunentzako bazkaria barne. <br \/>La ONG Alboan, en colaboraci\u00f3n con el Colegio San Ignacio y el Centro Loyola, ha organizado una jornada solidaria que incluye una marcha por el centro de la ciudad y una comida para 400 personas.<\/p>\n","protected":false},"author":7,"featured_media":231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19,20],"tags":[],"class_list":["post-285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ekitaldi-itxita","category-jardunaldi-solidarioak"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bazkari solidarioa Iru\u00f1ean - Eventos Alboan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bazkari solidarioa Iru\u00f1ean - Eventos Alboan\" \/>\n<meta property=\"og:description\" content=\"Igandean, urriaren 20an, Iru\u00f1ea mobilizatuko da Libanoko gatazkak kaltetutako pertsonei babesa emateko. Alboan Fundazioak, San Ignacio Ikastetxearekin eta Loyola Zentroarekin elkarlanean, elkartasun jardunaldi bat antolatu du hiriko erdigunetik martxa bat eta 400 lagunentzako bazkaria barne. La ONG Alboan, en colaboraci\u00f3n con el Colegio San Ignacio y el Centro Loyola, ha organizado una jornada solidaria que incluye una marcha por el centro de la ciudad y una comida para 400 personas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventos Alboan\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T13:45:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T15:40:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1550\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alboan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"alboan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/\"},\"author\":{\"name\":\"alboan\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#\\\/schema\\\/person\\\/e97f0d2d7d28d98f4e3617fc5aed8357\"},\"headline\":\"Bazkari solidarioa Iru\u00f1ean\",\"datePublished\":\"2025-03-19T13:45:42+00:00\",\"dateModified\":\"2025-04-28T15:40:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/\"},\"wordCount\":92,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/jornada-solidaria-pamplona.jpg\",\"articleSection\":[\"EKITALDI ITXITA\",\"Jardunaldi Solidarioak\"],\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/\",\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/\",\"name\":\"Bazkari solidarioa Iru\u00f1ean - Eventos Alboan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/jornada-solidaria-pamplona.jpg\",\"datePublished\":\"2025-03-19T13:45:42+00:00\",\"dateModified\":\"2025-04-28T15:40:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/jornada-solidaria-pamplona.jpg\",\"contentUrl\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/jornada-solidaria-pamplona.jpg\",\"width\":1550,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/bazkari-solidarioa-irunean\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bazkari solidarioa Iru\u00f1ean\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/\",\"name\":\"Eventos Alboan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#organization\",\"name\":\"Eventos Alboan\",\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/logoalboan.svg\",\"contentUrl\":\"https:\\\/\\\/eventos.alboan.org\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/03\\\/logoalboan.svg\",\"width\":220,\"height\":72,\"caption\":\"Eventos Alboan\"},\"image\":{\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/#\\\/schema\\\/person\\\/e97f0d2d7d28d98f4e3617fc5aed8357\",\"name\":\"alboan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g\",\"caption\":\"alboan\"},\"sameAs\":[\"http:\\\/\\\/luchacreativa.com\"],\"url\":\"https:\\\/\\\/eventos.alboan.org\\\/eu\\\/author\\\/f1b02aca489fcaec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bazkari solidarioa Iru\u00f1ean - Eventos Alboan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/","og_locale":"eu_ES","og_type":"article","og_title":"Bazkari solidarioa Iru\u00f1ean - Eventos Alboan","og_description":"Igandean, urriaren 20an, Iru\u00f1ea mobilizatuko da Libanoko gatazkak kaltetutako pertsonei babesa emateko. Alboan Fundazioak, San Ignacio Ikastetxearekin eta Loyola Zentroarekin elkarlanean, elkartasun jardunaldi bat antolatu du hiriko erdigunetik martxa bat eta 400 lagunentzako bazkaria barne. La ONG Alboan, en colaboraci\u00f3n con el Colegio San Ignacio y el Centro Loyola, ha organizado una jornada solidaria que incluye una marcha por el centro de la ciudad y una comida para 400 personas.","og_url":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/","og_site_name":"Eventos Alboan","article_published_time":"2025-03-19T13:45:42+00:00","article_modified_time":"2025-04-28T15:40:09+00:00","og_image":[{"width":1550,"height":600,"url":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg","type":"image\/jpeg"}],"author":"alboan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"alboan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#article","isPartOf":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/"},"author":{"name":"alboan","@id":"https:\/\/eventos.alboan.org\/eu\/#\/schema\/person\/e97f0d2d7d28d98f4e3617fc5aed8357"},"headline":"Bazkari solidarioa Iru\u00f1ean","datePublished":"2025-03-19T13:45:42+00:00","dateModified":"2025-04-28T15:40:09+00:00","mainEntityOfPage":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/"},"wordCount":92,"commentCount":0,"publisher":{"@id":"https:\/\/eventos.alboan.org\/eu\/#organization"},"image":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#primaryimage"},"thumbnailUrl":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg","articleSection":["EKITALDI ITXITA","Jardunaldi Solidarioak"],"inLanguage":"eu-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/","url":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/","name":"Bazkari solidarioa Iru\u00f1ean - Eventos Alboan","isPartOf":{"@id":"https:\/\/eventos.alboan.org\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#primaryimage"},"image":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#primaryimage"},"thumbnailUrl":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg","datePublished":"2025-03-19T13:45:42+00:00","dateModified":"2025-04-28T15:40:09+00:00","breadcrumb":{"@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#primaryimage","url":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg","contentUrl":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg","width":1550,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/eventos.alboan.org\/eu\/bazkari-solidarioa-irunean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eventos.alboan.org\/eu\/"},{"@type":"ListItem","position":2,"name":"Bazkari solidarioa Iru\u00f1ean"}]},{"@type":"WebSite","@id":"https:\/\/eventos.alboan.org\/eu\/#website","url":"https:\/\/eventos.alboan.org\/eu\/","name":"Eventos Alboan","description":"","publisher":{"@id":"https:\/\/eventos.alboan.org\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventos.alboan.org\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/eventos.alboan.org\/eu\/#organization","name":"Eventos Alboan","url":"https:\/\/eventos.alboan.org\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/eventos.alboan.org\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/logoalboan.svg","contentUrl":"https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/logoalboan.svg","width":220,"height":72,"caption":"Eventos Alboan"},"image":{"@id":"https:\/\/eventos.alboan.org\/eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eventos.alboan.org\/eu\/#\/schema\/person\/e97f0d2d7d28d98f4e3617fc5aed8357","name":"alboan","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/174899e15bb9f0b34f65d33f48d526280d4c08638b8a7e70d060027959a49e10?s=96&d=mm&r=g","caption":"alboan"},"sameAs":["http:\/\/luchacreativa.com"],"url":"https:\/\/eventos.alboan.org\/eu\/author\/f1b02aca489fcaec\/"}]}},"spectra_custom_meta":{"_pingme":["1"],"_encloseme":["1"],"_yoast_wpseo_primary_category":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"adv-header-id-meta":[""],"footer-sml-layout":[""],"stick-header-meta":[""],"header-main-stick-meta":[""],"header-above-stick-meta":[""],"header-below-stick-meta":[""],"site-post-title":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"ast-featured-img":[""],"ast-breadcrumbs-content":[""],"theme-transparent-header-meta":[""],"ast-banner-title-visibility":[""],"ast-global-header-display":[""],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["231"],"_last_translation_edit_mode":["native-editor"],"_wpml_word_count":["206"],"_edit_lock":["1745855970:21"],"_edit_last":["21"],"_wpml_media_has_media":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_uag_css_file_name":["uag-css-285.css"],"_uag_js_file_name":["uag-js-285.js"],"_cmplz_scanned_post":["1"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:11;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:2;s:18:\"uagb\/buttons-child\";i:2;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:13;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:1;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:2;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1777019495"],"_uag_page_assets":["a:9:{s:3:\"css\";s:87346:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-countdown{display:flex;justify-content:center;text-align:center}.wp-block-uagb-countdown .wp-block-uagb-countdown__box{transition:box-shadow .2s ease}.wp-block-uagb-countdown__box{position:relative;display:flex;flex-direction:column;width:155px;height:155px;aspect-ratio:1;justify-content:center}@media(max-width: 976px){.wp-block-uagb-countdown__box{width:100px;height:100px}}@media(max-width: 767px){.wp-block-uagb-countdown__box{width:65px;height:65px}}.wp-block-uagb-countdown__time{font-size:52px}@media(max-width: 976px){.wp-block-uagb-countdown__time{font-size:32px}}.wp-block-uagb-countdown__label{font-size:14px}@media(max-width: 976px){.wp-block-uagb-countdown__label{font-size:12px}}.wp-block-uagb-countdown .wp-block-uagb-countdown-innerblocks{text-align:initial}html:not([dir=rtl]) .wp-block-uagb-countdown__box:not(:last-child){margin-right:38px}html:not([dir=rtl]) .wp-block-uagb-countdown__box:not(:last-child) .wp-block-uagb-countdown__time::after{position:absolute;right:0}html:not([dir=rtl]) .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-seconds .wp-block-uagb-countdown__time-seconds::after{display:none}html:not([dir=rtl]) .wp-block-uagb-countdown>.wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-seconds:not(:last-child){margin-right:unset}.wp-block-uagb-countdown-innerblocks{display:none}html[dir=rtl] .wp-block-uagb-countdown__box:not(:first-child){margin-right:38px}html[dir=rtl] .wp-block-uagb-countdown__box:not(:first-child) .wp-block-uagb-countdown__time::before{position:absolute;right:0}body[class*=astra] .wp-block-uagb-countdown{line-height:normal}.wp-block-uagb-container.uagb-block-20416a3c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-20416a3c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-20416a3c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-20416a3c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-20416a3c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-20416a3c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-20416a3c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-cba13926.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: center;justify-content: center;align-self: center;}.uagb-block-cba13926 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-cba13926.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 1550px;height: auto;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-cba13926.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cba13926.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-3dfd899b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3dfd899b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3dfd899b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3dfd899b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3dfd899b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3dfd899b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-3dfd899b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading {background: var(--ast-global-color-8);padding-top: 30px;padding-right: 20px;padding-bottom: 30px;padding-left: 60px;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac .uagb-heading-text{text-transform: uppercase;}.wp-block-uagb-container.uagb-block-91948dea .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-91948dea .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-91948dea .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-91948dea .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-91948dea .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91948dea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91948dea > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1440px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-91948dea{box-shadow: 0px 0px   #00000070 ;padding-top: 60px;padding-bottom: 60px;padding-left: 60px;padding-right: 60px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2151326c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2151326c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2151326c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2151326c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2151326c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2151326c{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2151326c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2151326c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-68fd1db2.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap{width: 100%;align-items: center;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button {width: 100%;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .wp-block-button__link:hover{background: #f1943c;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .wp-block-button__link:focus{background: #f1943c;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-button__wrapper .uagb-buttons-repeater{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-e4bb4102.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-e4bb4102.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-button__link{text-transform: normal;text-decoration: none;}.uagb-block-77983cb4.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap{width: 100%;align-items: center;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button {width: 100%;}.wp-block-uagb-buttons .uagb-block-31134bc4 .wp-block-button__link:hover{background: #f1943c;}.wp-block-uagb-buttons .uagb-block-31134bc4 .wp-block-button__link:focus{background: #f1943c;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-button__wrapper .uagb-buttons-repeater{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-31134bc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-31134bc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 12px;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 12px;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 3px;width: 100%;border-color: #ef811a;margin-bottom: 10px;}.wp-block-uagb-advanced-heading.uagb-block-2b964e83 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6999edee.wp-block-uagb-advanced-heading {margin-top: -20px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6999edee.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6999edee.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6999edee.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6999edee.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f034d852.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 3px;width: 100%;border-color: #ef811a;margin-bottom: 10px;}.wp-block-uagb-advanced-heading.uagb-block-f034d852 .uagb-heading-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec.wp-block-uagb-advanced-heading {margin-top: -20px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a4354eec .uagb-heading-text{font-size: 14px;}.wp-block-uagb-advanced-heading.uagb-block-00848177.wp-block-uagb-advanced-heading {padding-left: 20px;}.wp-block-uagb-advanced-heading.uagb-block-00848177.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-00848177.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00848177.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00848177.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-00848177 .uagb-heading-text{font-weight: 700;}.wp-block-uagb-container.uagb-block-df34dd27 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-df34dd27 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-df34dd27 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-df34dd27 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-df34dd27 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-df34dd27{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-df34dd27 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-df34dd27{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-style: solid;border-color: var(--ast-global-color-7);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5fba0dba .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fba0dba .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fba0dba .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fba0dba .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fba0dba .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fba0dba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fba0dba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5fba0dba{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-style: solid;border-color: var(--ast-global-color-7);flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-822ce3de .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-822ce3de .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-822ce3de .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-822ce3de .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-822ce3de .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-822ce3de{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-822ce3de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-822ce3de{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-101c4ac7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-101c4ac7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-101c4ac7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-101c4ac7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-f2c5b102 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2c5b102 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2c5b102 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2c5b102 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2c5b102 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2c5b102{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2c5b102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f2c5b102{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-160faa78.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ef811a;}.wp-block-uagb-advanced-heading.uagb-block-160faa78.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-160faa78.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-160faa78.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-160faa78.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-160faa78 .uagb-heading-text{font-weight: 800;}.wp-block-uagb-container.uagb-block-4c274995 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4c274995 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4c274995 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4c274995 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4c274995 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4c274995{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4c274995 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4c274995{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-style: solid;border-color: var(--ast-global-color-7);flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303.wp-block-uagb-advanced-heading {padding-left: 20px;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa53f303 .uagb-heading-text{font-weight: 700;}.wp-block-uagb-container.uagb-block-9b8dec26 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9b8dec26 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9b8dec26 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9b8dec26 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9b8dec26 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b8dec26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b8dec26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9b8dec26{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-style: solid;border-color: var(--ast-global-color-7);flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c21d967a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c21d967a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c21d967a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c21d967a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c21d967a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c21d967a{max-width: 75%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c21d967a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c21d967a{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-624cd772.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-624cd772.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-624cd772.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-624cd772.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-9f03921b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f03921b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f03921b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f03921b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f03921b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f03921b{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f03921b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9f03921b{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-30caed17.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ef811a;}.wp-block-uagb-advanced-heading.uagb-block-30caed17.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-30caed17.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-30caed17.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-30caed17.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-30caed17 .uagb-heading-text{font-weight: 800;}.wp-block-uagb-container.uagb-block-37627e51 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37627e51 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37627e51 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37627e51 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37627e51 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37627e51{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37627e51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-37627e51{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-c013c43b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 678px;height: auto;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-c013c43b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c013c43b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ef097ff.wp-block-uagb-countdown{justify-content: center;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box-seconds{display: none;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box{aspect-ratio: auto;width: 160px;height: auto;flex-direction: column;justify-content: center;align-items: center;background-color: #eeeeee;padding-top: 15px;padding-right: 10px;padding-bottom: 15px;padding-left: 10px;row-gap: 4px;column-gap: 4px;box-shadow: 0px 50px 50px -30px rgb(0 0 0 \/ 15%) ;border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-style: none;}.uagb-block-1ef097ff.wp-block-uagb-countdown:hover .wp-block-uagb-countdown__box{box-shadow: 0px 0px 0 rgb(0 0 0 \/ 15%) ;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-minutes:not(:last-child){margin-right: unset;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-hours:not(:last-child){margin-right: 20px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-days:not(:last-child){margin-right: 20px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__time{font-style: normal;font-size: 52px;color: var(--ast-global-color-2);}.uagb-block-1ef097ff.wp-block-uagb-countdown div.wp-block-uagb-countdown__label{align-self: unset;font-style: normal;font-size: 11px;color: var(--ast-global-color-6);}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-20416a3c{width: 100%;}.wp-block-uagb-container.uagb-block-20416a3c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1550px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3dfd899b{width: 100%;}.wp-block-uagb-container.uagb-block-3dfd899b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91948dea{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91948dea > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-91948dea{padding-top: 60px;padding-bottom: 60px;padding-left: 60px;padding-right: 60px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2151326c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2151326c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2151326c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-e4bb4102.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-31134bc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-df34dd27{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-df34dd27 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-df34dd27{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fba0dba{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fba0dba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5fba0dba{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-822ce3de{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-822ce3de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-822ce3de{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2c5b102{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2c5b102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-f2c5b102{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4c274995{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4c274995 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4c274995{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b8dec26{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b8dec26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9b8dec26{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c21d967a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c21d967a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c21d967a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f03921b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f03921b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9f03921b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37627e51{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37627e51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-37627e51{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 678px;height: auto;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box{width: 75px;height: auto;flex-direction: column;justify-content: center;align-items: center;padding-top: 15px;padding-right: 10px;padding-bottom: 15px;padding-left: 10px;row-gap: 4px;column-gap: 4px;border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-style: none;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-minutes:not(:last-child){margin-right: unset;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-hours:not(:last-child){margin-right: 40px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-days:not(:last-child){margin-right: 40px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__time{font-size: 32px;}.uagb-block-1ef097ff.wp-block-uagb-countdown div.wp-block-uagb-countdown__label{align-self: unset;font-size: 11px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-20416a3c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-20416a3c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-cba13926.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 1550px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3dfd899b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-3dfd899b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-cd35c1ac.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 20px;padding-bottom: 0px;padding-left: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-91948dea{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-91948dea > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-91948dea{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2151326c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2151326c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2151326c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-68fd1db2.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-e4bb4102.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-e4bb4102 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-77983cb4.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-31134bc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-31134bc4 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-df34dd27{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-df34dd27 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-df34dd27{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fba0dba{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fba0dba > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5fba0dba{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-822ce3de{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-822ce3de > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-822ce3de{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2c5b102{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2c5b102 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f2c5b102{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4c274995{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4c274995 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4c274995{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9b8dec26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9b8dec26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9b8dec26{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: var(--ast-global-color-7);flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c21d967a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c21d967a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c21d967a{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f03921b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f03921b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9f03921b{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37627e51{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37627e51 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-37627e51{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-c013c43b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 678px;height: auto;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box{width: 60px;height: auto;flex-direction: column;justify-content: center;align-items: center;padding-top: 12px;padding-right: 12px;padding-bottom: 12px;padding-left: 12px;row-gap: 2px;column-gap: 2px;border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-style: none;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-minutes:not(:last-child){margin-right: unset;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-hours:not(:last-child){margin-right: 15px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__box.wp-block-uagb-countdown__box-days:not(:last-child){margin-right: 15px;}.uagb-block-1ef097ff.wp-block-uagb-countdown .wp-block-uagb-countdown__time{font-size: 30px;}.uagb-block-1ef097ff.wp-block-uagb-countdown div.wp-block-uagb-countdown__label{align-self: unset;font-size: 10px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-container.uagb-block-3d150865 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3d150865 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3d150865 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3d150865 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3d150865 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3d150865{max-width: 760px;width: 100%;}.wp-block-uagb-container.uagb-block-3d150865{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-style: none;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 760px !important;}.wp-block-uagb-container.uagb-block-3d150865.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-3d150865.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-container.uagb-block-253a9fd4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-253a9fd4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-253a9fd4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-253a9fd4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-253a9fd4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-253a9fd4{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-253a9fd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-253a9fd4{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7bdd3e7c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7bdd3e7c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7bdd3e7c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7bdd3e7c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7bdd3e7c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7bdd3e7c{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7bdd3e7c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7bdd3e7c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bb5ce33c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bb5ce33c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bb5ce33c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bb5ce33c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bb5ce33c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb5ce33c{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb5ce33c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bb5ce33c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-3d150865{width: 100%;}.wp-block-uagb-container.uagb-block-3d150865{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;max-width:  !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-253a9fd4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-253a9fd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-253a9fd4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7bdd3e7c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7bdd3e7c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7bdd3e7c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb5ce33c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb5ce33c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bb5ce33c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-3d150865{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-3d150865{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: none;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-253a9fd4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-253a9fd4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-253a9fd4{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7bdd3e7c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7bdd3e7c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7bdd3e7c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb5ce33c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb5ce33c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bb5ce33c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-fcaf78f6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-fcaf78f6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: fill;width: px;height: auto;}.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-af7bbbfa.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-af7bbbfa.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:692:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-e4bb4102' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-31134bc4' );\n});\n\t\t\twindow.addEventListener( 'load', function() {\n\t\t\t\tUAGBCountdown.init( '.uagb-block-1ef097ff', {\"block_id\":\"1ef097ff\",\"endDateTime\":\"2024-10-18T23:00:00.000Z\",\"showDays\":true,\"showHours\":true,\"showMinutes\":true,\"isFrontend\":true,\"timerEndAction\":\"zero\",\"redirectURL\":\"\",\"timerType\":\"date\",\"evergreenDays\":0,\"evergreenHrs\":0,\"evergreenMinutes\":0,\"campaignID\":\"\",\"resetDays\":30,\"reloadOnExpire\":true,\"autoReload\":false} );\n\t\t\t});\n\t\t });\";s:18:\"current_block_list\";a:16:{i:0;s:14:\"uagb\/container\";i:1;s:10:\"uagb\/image\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:25:\"uagb\/animations-extension\";i:7;s:12:\"uagb\/buttons\";i:8;s:18:\"uagb\/buttons-child\";i:9;s:14:\"uagb\/countdown\";i:10;s:14:\"core\/paragraph\";i:11;s:11:\"core\/search\";i:12;s:10:\"core\/group\";i:13;s:12:\"core\/heading\";i:14;s:17:\"core\/latest-posts\";i:15;s:20:\"core\/latest-comments\";i:16;s:13:\"core\/archives\";i:17;s:15:\"core\/categories\";i:20;s:10:\"core\/image\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778226998\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg",1550,600,false],"thumbnail":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona-150x150.jpg",150,150,true],"medium":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona-300x116.jpg",300,116,true],"medium_large":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona-768x297.jpg",768,297,true],"large":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona-1024x396.jpg",1024,396,true],"1536x1536":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona-1536x595.jpg",1536,595,true],"2048x2048":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg",1550,600,false],"gform-image-choice-sm":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg",300,116,false],"gform-image-choice-md":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg",400,155,false],"gform-image-choice-lg":["https:\/\/eventos.alboan.org\/wp-content\/uploads\/sites\/11\/2025\/03\/jornada-solidaria-pamplona.jpg",600,232,false]},"uagb_author_info":{"display_name":"alboan","author_link":"https:\/\/eventos.alboan.org\/eu\/author\/f1b02aca489fcaec\/"},"uagb_comment_info":0,"uagb_excerpt":"Igandean, urriaren 20an, Iru\u00f1ea mobilizatuko da Libanoko gatazkak kaltetutako pertsonei babesa emateko. Alboan Fundazioak, San Ignacio Ikastetxearekin eta Loyola Zentroarekin elkarlanean, elkartasun jardunaldi bat antolatu du hiriko erdigunetik martxa bat eta 400 lagunentzako bazkaria barne. La ONG Alboan, en colaboraci\u00f3n con el Colegio San Ignacio y el Centro Loyola, ha organizado una jornada solidaria que&hellip;","_links":{"self":[{"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/posts\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/comments?post=285"}],"version-history":[{"count":2,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/posts\/285\/revisions"}],"predecessor-version":[{"id":310,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/posts\/285\/revisions\/310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/media\/231"}],"wp:attachment":[{"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/media?parent=285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/categories?post=285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventos.alboan.org\/eu\/wp-json\/wp\/v2\/tags?post=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}